{"id":48587,"date":"2021-04-12T15:45:26","date_gmt":"2021-04-12T19:45:26","guid":{"rendered":"https:\/\/nrsplus.com\/precios\/"},"modified":"2026-04-23T11:48:16","modified_gmt":"2026-04-23T15:48:16","slug":"precios","status":"publish","type":"page","link":"https:\/\/nrsplus.com\/es\/precios\/","title":{"rendered":"Precios"},"content":{"rendered":"<h1 class=\"text-center new\">Precios<\/h1><div class=\"pay-logo\"><div class=\"container\"><div class=\"row\"><div class=\"col-md-6\"><div class=\"logo-nrs\"><a href=\"#\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/pay-logo.png\" alt=\"pay-logo\" \/><\/a><\/div><\/div><div class=\"col-md-6\"><div class=\"nrs-price\"><ul class=\"list-unstyled d-flex d-inline-flex m-0\"><li><a href=\"#\">(833) 289-2767<\/a><\/li><li><a href=\"#\">NRSPLUS.COM\/PRICING<\/a><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><div class=\"holder\"><div class=\"choose-section\"><div class=\"container\"><div class=\"pricing-sheets\"><\/div><div class=\"d-lg-block d-md-block d-none d-sm-none\"><h2>ELIJA SU HARDWARE NRS POS<\/h2><p>PRECIOS DE EQUIPOS; IMPUESTOS ADICIONALES<\/p><table class=\"nrs-pos-software-table \"><thead><tr class=\"header-category\"><th scope=\"col\" style=\"background-color: transparent; border: none;\"><\/th><th scope=\"colgroup\" colspan=\"2\" class=\"header-countertop\">PAQUETES POS DE MOSTRADOR<\/th><th scope=\"colgroup\" colspan=\"2\" class=\"header-tablet\">PAQUETES POS DE TABLETA<\/th><th scope=\"colgroup\" class=\"header-kiosk\">TERMINAL DE QUIOSCO<\/th><\/tr><tr><th style=\"background-color: transparent; border: none;\"><\/th><th scope=\"col\" class=\"col-header col-puma\"><div>PUMA\r\n\r\n\r\nPOS<\/div><div class=\"price\">$1,299<\/div><div class=\"regular-price\">(Precio de Lista: $1,999)<\/div><\/th><th scope=\"col\" class=\"col-header col-cheetah\"><div>CHEETAH\r\n\r\n\r\nPOS<\/div><div class=\"price\">$1,799<\/div><div class=\"regular-price\">(Precio de Lista: $2,799)<\/div><\/th><th scope=\"col\" class=\"col-header col-panther-ws\"><div>PANTHER\r\n\r\n\r\nESTACI\u00d3N DE TRABAJO<\/div><div class=\"price\">$1,199<\/div><\/th><th scope=\"col\" class=\"col-header col-panther-tb\"><div>PANTHER\r\n\r\n\r\n<span class=\"text-lg-nowrap\">PAQUETE DE TABLETA<\/span><\/div><div class=\"price\">$499<\/div><\/th><th scope=\"col\" class=\"col-header col-kiosk\"><div>QUIOSCO DE AUTOPEDIDO<\/div><div class=\"price\">$1,595<\/div><div class=\"regular-price\">(Precio de Lista: $2,495)<\/div><div class=\"note\">Se Requiere NRS POS<\/div><\/th><\/tr><\/thead><tbody><tr class=\"row-incl-hardware\"><th scope=\"row\" rowspan=\"5\" class=\"sidebar-header sidebar-hardware\"><span>HARDWARE INCLUIDO<\/span><\/th><td class=\"col-puma content-cell\">Nuestro POS Cl\u00e1sico<\/td><td class=\"col-cheetah content-cell\">POS de Alta Potencia<\/td><td class=\"col-panther-ws content-cell\">Elegante POS de Tableta<\/td><td class=\"col-panther-tb content-cell\">Tableta Android<\/td><td class=\"col-kiosk content-cell\">Quiosco de Autopedido<\/td><\/tr><tr class=\"row-incl-hardware\"><td class=\"col-puma content-cell\">Impresora T\u00e9rmica de Recibos<\/td><td class=\"col-cheetah content-cell\">Impresora T\u00e9rmica de Recibos<\/td><td class=\"col-panther-ws content-cell\">Impresora T\u00e9rmica de Recibos<\/td><td class=\"col-panther-tb content-cell\">Impresora T\u00e9rmica de Recibos<\/td><td class=\"col-kiosk content-cell\">Impresora de Recibos Incorporada<\/td><\/tr><tr class=\"row-incl-hardware\"><td class=\"col-puma content-cell\">Esc\u00e1ner de C\u00f3digo de Barras \/ Identificaci\u00f3n<\/td><td class=\"col-cheetah content-cell\">Esc\u00e1ner de C\u00f3digo de Barras \/ Identificaci\u00f3n<\/td><td class=\"col-panther-ws content-cell\">Esc\u00e1ner de C\u00f3digo de Barras \/ Identificaci\u00f3n<\/td><td class=\"col-panther-tb content-cell\">Esc\u00e1ner de C\u00f3digo de Barras \/ Identificaci\u00f3n<\/td><td class=\"col-kiosk content-cell\">Esc\u00e1ner de C\u00f3digo de Barras<\/td><\/tr><tr class=\"row-incl-hardware\"><td class=\"col-puma content-cell\">Pantalla Orientada al Cliente<\/td><td class=\"col-cheetah content-cell\">Pantalla Orientada al Cliente<\/td><td class=\"col-panther-ws content-cell\">Pantalla Orientada al Cliente<\/td><td class=\"col-panther-tb content-cell\">N\/A<\/td><td class=\"col-kiosk content-cell\">Pantalla T\u00e1ctil<\/td><\/tr><tr class=\"row-incl-hardware\"><td class=\"col-puma content-cell\">Caj\u00f3n de Dinero Resistente<\/td><td class=\"col-cheetah content-cell\">Caj\u00f3n de Dinero Resistente<\/td><td class=\"col-panther-ws content-cell\">Caj\u00f3n de Dinero Resistente<\/td><td class=\"col-panther-tb content-cell\">Caj\u00f3n de Dinero Resistente<\/td><td class=\"col-kiosk content-cell\">Soporte de Piso (+$200 Extra)<\/td><\/tr><tr class=\"row-nrs-pay\"><th scope=\"row\" rowspan=\"3\" class=\"sidebar-header sidebar-pay\"><span>NRS PAY<\/span><\/th><td class=\"col-puma content-cell\">NRS Pay <strong>Opcional<\/strong><\/td><td class=\"col-cheetah content-cell\">NRS Pay <strong>Requerido<\/strong><\/td><td class=\"col-panther-ws content-cell\">NRS Pay <strong>Requerido<\/strong><\/td><td class=\"col-panther-tb content-cell\">NRS Pay <strong>Requerido<\/strong><\/td><td class=\"col-kiosk content-cell\">NRS Pay <strong>Requerido<\/strong><\/td><\/tr><tr class=\"row-nrs-pay\"><td class=\"col-puma content-cell\">Lector de Tarjetas de Cr\u00e9dito\r\n\r\n\r\n<strong>Solo incluido para tiendas con NRS Pay<\/strong><\/td><td class=\"col-cheetah content-cell\">Lector de Tarjetas de Cr\u00e9dito\r\n\r\n\r\n<strong>Incluido (valor de $200)<\/strong><\/td><td class=\"col-panther-ws content-cell\">Tableta de Procesamiento de Pagos\r\n\r\n\r\n<strong>Incluida (valor de $400)<\/strong><\/td><td class=\"col-panther-tb content-cell\">Tableta de Procesamiento de Pagos\r\n\r\n\r\n<strong>Incluida (valor de $400)<\/strong><\/td><td class=\"col-kiosk content-cell\">Lector de Tarjetas de Cr\u00e9dito\r\n\r\n\r\n<strong>Incluido (valor de $200)<\/strong><\/td><\/tr><\/tbody><tfoot><tr><td><\/td><td><\/td><td><\/td><td colspan=\"2\" class=\"footer-note\">\u00a1Tambi\u00e9n puede <strong>TRAER SU PROPIA TABLETA<\/strong> y pagar $0 por el hardware! Solo descargue la aplicaci\u00f3n Panther en su tableta Android.<\/td><\/tr><\/tfoot><\/table><\/div><div style=\"display: none!important;\" class=\"TOTAL-HIDDEN choose-table d-none d-lg-block d-md-block d-sm-none\"><div class=\"table-responsive\"><table class=\"table\"><tbody><tr><th rowspan=\"3\"><h4>ELIJA SU<\/h4><h3>HARDWARE<\/h3><h5>NRS POS<\/h5>PRECIOS DE EQUIPOS; IMPUESTOS ADICIONALES<\/th><th style=\"font-size: 24px; vertical-align: middle; text-align: center; font-weight: 600; color: #fff; padding: 18px 5px;\">POS CON <img decoding=\"async\" class=\"img-fluid\" style=\"width: 113px;\" src=\"\/wp-content\/uploads\/2023\/05\/text-cashdiscount-plain.png\" alt=\"free-logo\" \/><\/th><th style=\"font-size: 24px; vertical-align: middle; text-align: center; font-weight: 600; color: #fff; padding: 18px 5px;\">POS CON <img decoding=\"async\" class=\"img-fluid\" style=\"width: 100px;\" src=\"\/wp-content\/uploads\/2023\/05\/text-cleanrate-plain.png\" alt=\"nrs\" \/><\/th><th>SOLO POS SIN NRS PAY<\/th><\/tr><tr><td>COMPRA<\/td><td>COMPRA<\/td><td>COMPRA<\/td><\/tr><tr><td><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/deal-logo.png\" alt=\"free-logo\" \/><h5>$599<\/h5>(Regularmente $1,299)<\/td><td><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/deal-logo-1.png\" alt=\"free-logo\" \/><h5>$699<\/h5>(Regularmente $1,299)<\/td><td><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/deal-logo-2.png\" alt=\"free-logo\" \/><h5>$999<\/h5>(Regularmente $1,299)<\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Choose Clean Rate or Cash Discount - Enjoy savings on NRS software plans and features\">i <\/span><strong>NRS PAY<\/strong> Nuestro Procesamiento de Tarjetas de Cr\u00e9dito de Baja Tasa<\/td><td>Por <strong>1 A\u00f1o<\/strong><\/td><td>Por <strong>1 A\u00f1o<\/strong><\/td><td>Opcional<\/td><\/tr><tr><td style=\"vertical-align: middle;\"><h3>HARDWARE<\/h3><span class=\"note tooltip\" title=\"Easy to use touch screen interface for cashiers and store managers\">i<\/span> Pantalla T\u00e1ctil para el Cajero<\/td><td style=\"vertical-align: middle;\"><h3><\/h3><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td style=\"vertical-align: middle;\"><h3><\/h3><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td style=\"vertical-align: middle;\"><h3><\/h3><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Large, sleek transaction screen keeps customers engaged\">i<\/span> Pantalla Orientada al Cliente<\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Durable printer uses refillable thermal paper; requires no ink cartridges\">i<\/span> Impresora T\u00e9rmica de Recibos<\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Speed up checkout with this bidirectional UPC code scanner \/ Use this handheld scanner to verify your customers' age\">i<\/span> Esc\u00e1ner de C\u00f3digo de Barras \/ Identificaci\u00f3n<\/td><td class=\"text-center\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td class=\"text-center\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td class=\"text-center\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Sturdy Cash Drawer: metal cash drawer with lock\">i<\/span> Caj\u00f3n de Dinero Resistente<\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Seamlessly integrates with your POS for quick and easy payment acceptance\">i<\/span> Lector de Tarjetas de Cr\u00e9dito <i>(Valor de $350)<\/i><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Disponible para Compra<\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Prevents data loss during power outage and protects your equipment from surges\">i<\/span> Unidad de Bater\u00eda de Respaldo<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Disponible para Compra<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Disponible para Compra<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Disponible para Compra<\/td><\/tr><tr class=\"light-blue-color\"><td><h3>Garant\u00eda<\/h3><span class=\"note tooltip\" title=\"Parts repair and replacement during first 90 days from purchase\">i<\/span> Garant\u00eda del Fabricante del 1er A\u00f1o<\/td><td style=\"vertical-align: middle;\"><h3><\/h3><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td style=\"vertical-align: middle;\"><h3><\/h3><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><td style=\"vertical-align: middle;\"><h3><\/h3><img decoding=\"async\" class=\"img-fluid\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\" \/><\/td><\/tr><tr class=\"light-blue-color\"><td><span class=\"note tooltip\" title=\"Up to 2 years - Pay just a 25% deductible for replacement parts after 1st year standard warranty expires\">i<\/span> Garant\u00eda Extendida de Reemplazos<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Disponible para Compra<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Disponible para Compra<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Disponible para Compra<\/td><\/tr><\/tbody><\/table><\/div><\/div><div class=\"choose-table table2 d-none d-lg-block d-md-block d-none d-sm-none\"><div class=\"table-responsive\"><table class=\"table\"><tbody><tr><th rowspan=\"5\"><h4>ELIJA SU<\/h4><h3>PLAN DE SOFTWARE (POS MRC)<\/h3>TARIFAS DE SERVICIO Y SOPORTE DE POS; IMPUESTOS ADICIONALES<p class=\"purple\">TARIFAS MENSUALES DE NRS PAY ADICIONALES SEG\u00daN EL PLAN<\/p><\/th><\/tr><tr><td>Comience por Menos<\/td><td>Herramientas Comerciales Profesionales<\/td><td>Comercio Electr\u00f3nico y Lealtad Incluidos<\/td><td>\u00a1Contacte a sus Clientes!<\/td><\/tr><tr><td><h2>B\u00c1SICO<\/h2><\/td><td><h2>PRO<\/h2><\/td><td><h2>AVANZADO<\/h2><\/td><td><h2>\u00c9LITE<\/h2><\/td><\/tr><tr><td><h5>$19.95\/mes*<\/h5>Sin NRS PAY: <strong>$29.95<\/strong>\/mes<\/td><td><h5>$34.95\/mes*<\/h5>Sin NRS PAY: <strong>$54.95<\/strong>\/mes<\/td><td><h5>$49.95\/mes*<\/h5>Sin NRS PAY: <strong>$74.95<\/strong>\/mes<\/td><td><h5>$79.95\/mes*<\/h5>Sin NRS PAY: <strong>$109.95<\/strong>\/mes<\/td><\/tr><tr><td><strong>PAGUE ANUALMENTE Y OBTENGA 1 MES GRATIS<\/strong><\/td><td><strong>PAGUE ANUALMENTE Y OBTENGA 1 MES GRATIS<\/strong><\/td><td><strong>PAGUE ANUALMENTE Y OBTENGA 1 MES GRATIS<\/strong><\/td><td><strong>PAGUE ANUALMENTE Y OBTENGA 1 MES GRATIS<\/strong><\/td><\/tr><tr><td colspan=\"5\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">CARACTER\u00cdSTICAS B\u00c1SICAS<\/h3><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Set up a dedicated user account for each of your employees\">i<\/span> N\u00famero de Usuarios<\/td><td><strong>3<\/strong> usuarios<\/td><td><strong>Ilimitados<\/strong> usuarios<\/td><td style=\"text-align:center\"><strong>Ilimitados<\/strong> usuarios<\/td><td style=\"text-align:center\"><strong>Ilimitados<\/strong> usuarios<\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Run your own free customer-facing ad(s) on your POS\">i<\/span> Ejecute sus Propios Anuncios Orientados al Cliente<\/td><td><strong>1<\/strong> anuncio<\/td><td><strong>3<\/strong> anuncios<\/td><td><strong>3<\/strong> anuncios<\/td><td style=\"text-align:center\"><strong>3<\/strong> anuncios<\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Control which users can access which features, and how\">i<\/span> Permisos de Usuario Personalizados<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Manage your prices and inventory, and get alerts when inventory runs low\">i<\/span> Gesti\u00f3n de Precios e Inventario<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Get detailed reporting about sales, payment methods, promotions and shift reports\">i<\/span> Estad\u00edsticas de Ventas<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Our dedicated Support team and web chat support are available for you\">i<\/span> Soporte por Tel\u00e9fono y Chat (7 d\u00edas a la semana)<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Manage your back-office remotely via mobile app and online merchant portal\">i<\/span> Gesti\u00f3n Remota: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Create your own store promotions on your POS and reward your customers\">i<\/span> Crear Promociones<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Sign up to receive a daily email summary of your sales\">i<\/span> Correos Electr\u00f3nicos de Resumen Diario de Ventas<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Use your PC to print labels for your products and shelves\">i<\/span> Imprimir Etiquetas: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"lavanda-color\"><td><h3 style=\"height:auto;\" class=\"mb-0\">HERRAMIENTAS COMERCIALES PRO<\/h3><\/td><td style=\"vertical-align: bottom; color: #8e92a7;\"><\/td><td style=\"vertical-align: middle;\"><h5 class=\"mb-0\">\u00a1Incluye Herramientas Comerciales Pro!<\/h5><\/td><td style=\"vertical-align: middle;\"><h5 class=\"mb-0\">\u00a1Incluye <strong class=\"big\">TODAS<\/strong> las Herramientas Comerciales Pro!<\/h5><\/td><td style=\"vertical-align: middle;text-align:center\"><h5 class=\"mb-0\">\u00a1Incluye <strong class=\"big\">TODAS<\/strong> las Herramientas Comerciales Pro!<\/h5><\/td><\/tr><tr class=\"lavanda-color\"><td><span class=\"note tooltip\" title=\"View and conveniently export your advanced stats, and get gross profit reporting\">i<\/span> Datos Avanzados (Valor de $14.95\/mes)<\/td><td style=\"vertical-align: bottom; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: bottom;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td style=\"vertical-align: bottom;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td style=\"vertical-align: middle;text-align:center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"lavanda-color\"><td><span class=\"note tooltip\" title=\"Customize orders with Item Modifiers, and integrate a special secondary printer for your kitchen\">i<\/span> Modificadores de Art\u00edculos e Impresora IP Remota (Valor de $14.95\/mes)*\r\n\r\n\r\n&#8211; Nota: Requiere Compra de Impresora IP de NRS<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"lavanda-color\"><td><span class=\"note tooltip\" title=\"Employees can clock in and out, so you will always know who was on shift, and when\">i<\/span> Reloj de Control de Empleados (Valor de $9.95\/mes)<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Reduce theft! POS transaction data is overlaid real-time onto your store's DVR surveillance footage\">i<\/span> Integraci\u00f3n de C\u00e1mara de Seguridad (Valor de $9.95\/mes)\r\n\r\n\r\n&#8211; Nota: Requiere Compra de Equipo por Separado<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\" style=\"vertical-align:middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Extend and keep track of store credit for your customers right on the POS\">i<\/span> Cuentas de Clientes (Valor de $9.95\/mes)<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Managers can approve cashier requests for restricted actions via the My Store App\">i<\/span> Anulaci\u00f3n de Gerente Remoto (Valor de $9.95\/mes)<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Get alerted on the My NRS Store app whenever there is suspicious activity at your POS\">i<\/span> Alertas Antirrobo (Valor de $9.95\/mes)<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr><td><span class=\"note tooltip\" title=\"Send your customers receipts via SMS message\">i<\/span> Recibos por SMS (Valor de $9.95\/mes)<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\" style=\"vertical-align: middle;\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"lavanda-color\"><td><span class=\"note tooltip\" title=\"Capture age verification with a compliant government ID scanner\">i<\/span> Escaneo de Identificaci\u00f3n\/Licencia (Valor de $4.95\/mes)<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"lavanda-color\"><td><span class=\"note tooltip\" title=\"Create, receive and track vendor orders\">i<\/span> Proveedores+ (Valor de $14.95\/mes)<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"light-green-color\"><td><h3 class=\"mb-0\">COMERCIO ELECTR\u00d3NICO (Valor de $29.95\/mes)<\/h3><\/td><td style=\"vertical-align: bottom; color: #8e92a7;\"><\/td><td style=\"vertical-align: bottom; color: #8e92a7;\"><\/td><td style=\"vertical-align: middle;\" class=\"text-center\"><h5 class=\"mb-0\">Incluye <strong class=\"big\">TODOS<\/strong> los Servicios de Comercio Electr\u00f3nico<\/h5><\/td><td style=\"vertical-align: middle;\" class=\"text-center\"><h5 class=\"mb-0\">Incluye <strong class=\"big\">TODOS<\/strong> los Servicios de Comercio Electr\u00f3nico<\/h5><\/td><\/tr><tr class=\"light-green-color\"><td><span class=\"note tooltip\" title=\"Start selling online with your own website; seamlessly integrated with the POS\">i<\/span> Su Propio Sitio Web de Comercio Electr\u00f3nico<\/td><td style=\"vertical-align: bottom; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: bottom; color: #8e92a7;\"><div style=\"color: #8e92a7;\">Complemento Disponible<\/div><\/td><td style=\"vertical-align: bottom;\" class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td style=\"vertical-align: bottom;\" class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"light-green-color\"><td><span class=\"note tooltip\" title=\"Using this handy mobile app, customers can locate your store and order ahead for pickup or delivery\">i<\/span> Vender en la Aplicaci\u00f3n de Compras BOSS Local<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\"><div style=\"color: #8e92a7;\">Complemento Disponible<\/div><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"light-green-color\"><td><span class=\"note tooltip\" title=\"Our delivery partners deliver orders from BR Club and your NRS Ecommerce website to your customers\">i<\/span> Red de Entrega de NRS<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\"><div style=\"color: #8e92a7;\">Complemento Disponible<\/div><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"light-orange-color\"><td style=\"vertical-align: bottom; height: auto;\"><h3 style=\"vertical-align: bottom; height: auto;margin-bottom:0;\">LEALTAD (Valor de $29.95\/mes)<\/h3><\/td><td style=\"vertical-align: bottom; color: #8e92a7;\"><\/td><td style=\"vertical-align: bottom; color: #8e92a7;\"><\/td><td style=\"vertical-align: middle;text-align:center\"><h5>Incluye <strong class=\"big\">TODOS<\/strong> los Programas de Lealtad<\/h5><\/td><td style=\"vertical-align: middle;text-align:center\"><h5>Incluye <strong class=\"big\">TODOS<\/strong> los Programas de Lealtad<\/h5><\/td><\/tr><tr class=\"light-orange-color\"><td><span class=\"note tooltip\" title=\"Offer your customers Points-per-Dollar rewards\">i<\/span> Programa de Puntos de Lealtad<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"light-orange-color\"><td><span class=\"note tooltip\" title=\"Offer your customers \u201cBuy X, Get 1 Free\u201d deals\">i<\/span> Programa de Clubes de Lealtad<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"light-orange-color\"><td><span class=\"note tooltip\" title=\"See your customers' recent transaction history, and items purchased in those transactions\">i<\/span> Historial de Transacciones del Cliente<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"light-pink-color\"><td style=\"vertical-align: bottom; height: auto;\"><h3 style=\"vertical-align: bottom; height: auto;margin-bottom:0;\">MARKETING (Valor de $79.90\/mes)<\/h3><\/td><td style=\"vertical-align: bottom; color: #8e92a7;\"><\/td><td style=\"vertical-align: bottom; color: #8e92a7;\"><\/td><td style=\"vertical-align: middle;text-align:center\"><\/td><td style=\"vertical-align: middle;text-align:center\"><h5>\u00a1Incluye <strong class=\"big\">TODOS<\/strong> los Servicios de Marketing!<\/h5><\/td><\/tr><tr class=\"light-pink-color\"><td><span class=\"note tooltip\" title=\"Send marketing text messages to your customers\">i <\/span> Contactar a mis Clientes<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"light-pink-color\"><td><span class=\"note tooltip\" title=\"Get custom AI recommendations for which products will sell best in your store\">i <\/span> Recomendaciones de Productos con IA<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td style=\"vertical-align: middle; color: #8e92a7;\">Complemento Disponible<\/td><td class=\"text-center\"><picture decoding=\"async\" class=\"img-fluid\"><source type=\"image\/webp\" srcset=\"\/wp-content\/uploads\/2021\/02\/circle.png.webp\"><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/02\/circle.png\" alt=\"circle\"><\/picture><\/td><\/tr><tr class=\"light-blue-color\"><td><span class=\"note tooltip\" title=\"No matter which software plan you're on, each additional POS is just $19.95\/mo. (with NRS Pay) -or- $29.95\/mo.* (without NRS PAY)\">i<\/span> <strong>TERMINALES POS ADICIONALES<\/strong><\/td><td colspan=\"4\" class=\"text-center\">Cualquier plan que elija: <strong>$19.95<\/strong>\/mes por cada m\u00e1quina adicional \u2013 Sin NRS PAY: <strong>$29.95<\/strong>\/mes.<\/td><\/tr><tr style=\"background:#c9edfb;\"><td colspan=\"5\"><strong style=\"font-weight: 700;color:#676868;\">TARIFA DE SOFTWARE PANTHER:<\/strong> A las tiendas Panther que tienen NRS Pay de Tarifa Plana O procesan menos de $10k en Descuento por Efectivo se les cobrar\u00e1 un adicional de $30<sup>\/mes<\/sup><\/td><\/tr><\/tbody><\/table><\/div><\/div><div class=\"mobile-display d-block d-md-none d-lg-none d-sm-block\"><div class=\"tab-list\" style=\"cursor: pointer;\"><div class=\"accordion\" id=\"accordion6\"><div class=\"card\"><div class=\"card-header\" id=\"mobileHardwareHeading\"><h5 class=\"mb-0\"><button style=\"margin-bottom: 10px;\" class=\"accordion-button btn btn-link level-1 collapsed\" data-bs-toggle=\"collapse\" data-bs-target=\"#mobileHardwareCollapse\" aria-controls=\"mobileHardwareCollapse\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5>ELIJA SU HARDWARE <span style=\"white-space: nowrap;\">(NRS POS)<\/span> PRECIOS DE EQUIPOS; IMPUESTOS ADICIONALES<\/h5><\/button><\/h5><\/div><div id=\"mobileHardwareCollapse\" class=\"accordion-collapse collapse\" aria-labelledby=\"mobileHardwareHeading\" data-bs-parent=\"#mobileAccordion\"><div class=\"card-body\"><div class=\"accordion\" id=\"hardwareCategoriesAccordion\"><div class=\"card\"><div class=\"card-header\" id=\"hardwareCategory1Heading\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link collapsed level-2\" data-bs-toggle=\"collapse\" data-bs-target=\"#hardwareCategory1Collapse\" aria-controls=\"hardwareCategory1Collapse\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-black mb-0\"><strong>PAQUETES POS DE MOSTRADOR<\/strong><\/h5><\/button><\/h5><\/div><div id=\"hardwareCategory1Collapse\" class=\"accordion-collapse collapse\" aria-labelledby=\"hardwareCategory1Heading\" data-bs-parent=\"#hardwareCategoriesAccordion\"><div class=\"card-body\"><div class=\"accordion\" id=\"countertopAccordion\"><div class=\"card\"><div class=\"card-header\" id=\"pumaPosHeading\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link collapsed level-3\" data-bs-toggle=\"collapse\" data-bs-target=\"#pumaPosCollapse\" aria-controls=\"pumaPosCollapse\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-black mb-0\"><strong>PUMA POS<\/strong><\/h5><\/button><\/h5><\/div><div id=\"pumaPosCollapse\" class=\"accordion-collapse collapse\" aria-labelledby=\"pumaPosHeading\" data-bs-parent=\"#countertopAccordion\"><div class=\"card-body\"><div class=\"choose-table new-table\"><table class=\"table\"><tbody><tr><td><h5>$1,299<\/h5>(Precio de Lista: $1,999)<\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\"><h3 style=\"height: auto;margin-bottom: 0;\">HARDWARE INCLUIDO<\/h3><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\">Nuestro POS Cl\u00e1sico<\/td><\/tr><tr class=\"light-green-color\"><td>Impresora T\u00e9rmica de Recibos<\/td><\/tr><tr class=\"light-green-color\"><td>Esc\u00e1ner de C\u00f3digo de Barras \/ Identificaci\u00f3n<\/td><\/tr><tr class=\"light-green-color\"><td>Pantalla Orientada al Cliente<\/td><\/tr><tr class=\"light-green-color\"><td>Caj\u00f3n de Dinero Resistente<\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">NRS PAY<\/h3><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\" style=\"background-color:#d7cae3!important;\">NRS Pay <strong>Opcional<\/strong><\/td><\/tr><tr class=\"light-purple-color\"><td>Lector de Tarjetas de Cr\u00e9dito <strong>Solo incluido para tiendas con NRS Pay<\/strong><\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><div class=\"card\"><div class=\"card-header\" id=\"cheetahPosHeading\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link collapsed level-3\" data-bs-toggle=\"collapse\" data-bs-target=\"#cheetahPosCollapse\" aria-controls=\"cheetahPosCollapse\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-black mb-0\"><strong>CHEETAH POS<\/strong><\/h5><\/button><\/h5><\/div><div id=\"cheetahPosCollapse\" class=\"accordion-collapse collapse\" aria-labelledby=\"cheetahPosHeading\" data-bs-parent=\"#countertopAccordion\"><div class=\"card-body\"><div class=\"choose-table new-table\"><table class=\"table\"><tbody><tr><td><h5>$1,799<\/h5>(Precio de Lista: $2,799)<\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\"><h3 style=\"height: auto;margin-bottom: 0;\">HARDWARE INCLUIDO<\/h3><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\">POS de Alta Potencia<\/td><\/tr><tr class=\"light-green-color\"><td>Impresora T\u00e9rmica de Recibos<\/td><\/tr><tr class=\"light-green-color\"><td>Esc\u00e1ner de C\u00f3digo de Barras \/ Identificaci\u00f3n<\/td><\/tr><tr class=\"light-green-color\"><td>Pantalla Orientada al Cliente<\/td><\/tr><tr class=\"light-green-color\"><td>Caj\u00f3n de Dinero Resistente<\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">NRS PAY<\/h3><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\" style=\"background-color:#d7cae3!important;\">NRS Pay <strong>Requerido<\/strong><\/td><\/tr><tr class=\"light-purple-color\"><td>Lector de Tarjetas de Cr\u00e9dito <strong>Incluido (valor de $200)<\/strong><\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"card\"><div class=\"card-header\" id=\"hardwareCategory2Heading\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link collapsed level-2\" data-bs-toggle=\"collapse\" data-bs-target=\"#hardwareCategory2Collapse\" aria-controls=\"hardwareCategory2Collapse\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-black mb-0\"><strong>PAQUETES POS DE TABLETA<\/strong><\/h5><\/button><\/h5><\/div><div id=\"hardwareCategory2Collapse\" class=\"accordion-collapse collapse\" aria-labelledby=\"hardwareCategory2Heading\" data-bs-parent=\"#hardwareCategoriesAccordion\"><div class=\"card-body\"><div class=\"accordion\" id=\"tabletAccordion\"><div class=\"card\"><div class=\"card-header\" id=\"pantherWorkstationHeading\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link collapsed level-3\" data-bs-toggle=\"collapse\" data-bs-target=\"#pantherWorkstationCollapse\" aria-controls=\"pantherWorkstationCollapse\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-black mb-0\"><strong>PANTHER ESTACI\u00d3N DE TRABAJO<\/strong><\/h5><\/button><\/h5><\/div><div id=\"pantherWorkstationCollapse\" class=\"accordion-collapse collapse\" aria-labelledby=\"pantherWorkstationHeading\" data-bs-parent=\"#tabletAccordion\"><div class=\"card-body\"><div class=\"choose-table new-table\"><table class=\"table\"><tbody><tr><td><h5>$1,199<\/h5><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\"><h3 style=\"height: auto;margin-bottom: 0;\">HARDWARE INCLUIDO<\/h3><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\">Elegante POS de Tableta<\/td><\/tr><tr class=\"light-green-color\"><td>Impresora T\u00e9rmica de Recibos<\/td><\/tr><tr class=\"light-green-color\"><td>Esc\u00e1ner de C\u00f3digo de Barras \/ Identificaci\u00f3n<\/td><\/tr><tr class=\"light-green-color\"><td>Pantalla Orientada al Cliente<\/td><\/tr><tr class=\"light-green-color\"><td>Caj\u00f3n de Dinero Resistente<\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">NRS PAY<\/h3><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\" style=\"background-color:#d7cae3!important;\">NRS Pay <strong>Requerido<\/strong><\/td><\/tr><tr class=\"light-purple-color\"><td>Tableta de Procesamiento de Pagos <strong>Incluida (valor de $400)<\/strong><\/td><\/tr><tr class=\"light-blue-color\"><td>\u00a1Tambi\u00e9n puede <strong>TRAER SU PROPIA TABLETA<\/strong> y pagar $0 por el hardware! Solo descargue la aplicaci\u00f3n Panther en su tableta Android.<\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><div class=\"card\"><div class=\"card-header\" id=\"pantherTabletHeading\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link collapsed level-3\" data-bs-toggle=\"collapse\" data-bs-target=\"#pantherTabletCollapse\" aria-controls=\"pantherTabletCollapse\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-black mb-0\"><strong>PANTHER PAQUETE DE TABLETA<\/strong><\/h5><\/button><\/h5><\/div><div id=\"pantherTabletCollapse\" class=\"accordion-collapse collapse\" aria-labelledby=\"pantherTabletHeading\" data-bs-parent=\"#tabletAccordion\"><div class=\"card-body\"><div class=\"choose-table new-table\"><table class=\"table\"><tbody><tr><td><h5>$499<\/h5><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\"><h3 style=\"height: auto;margin-bottom: 0;\">HARDWARE INCLUIDO<\/h3><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\">Tableta Android<\/td><\/tr><tr class=\"light-green-color\"><td>Impresora T\u00e9rmica de Recibos<\/td><\/tr><tr class=\"light-green-color\"><td>Esc\u00e1ner de C\u00f3digo de Barras \/ Identificaci\u00f3n<\/td><\/tr><tr class=\"light-green-color\"><td>Caj\u00f3n de Dinero Resistente<\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">NRS PAY<\/h3><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\" style=\"background-color:#d7cae3!important;\">NRS Pay <strong>Requerido<\/strong><\/td><\/tr><tr class=\"light-purple-color\"><td>Tableta de Procesamiento de Pagos <strong>Incluida (valor de $400)<\/strong><\/td><\/tr><tr class=\"light-blue-color\"><td>\u00a1Tambi\u00e9n puede <strong>TRAER SU PROPIA TABLETA<\/strong> y pagar $0 por el hardware! Solo descargue la aplicaci\u00f3n Panther en su tableta Android.<\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"card\"><div class=\"card-header\" id=\"kioskHeading\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link collapsed level-3\" data-bs-toggle=\"collapse\" data-bs-target=\"#kioskCollapse\" aria-controls=\"kioskCollapse\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-black mb-0\"><strong>QUIOSCO DE AUTOPEDIDO<\/strong><\/h5><\/button><\/h5><\/div><div id=\"kioskCollapse\" class=\"accordion-collapse collapse\" aria-labelledby=\"kioskHeading\" data-bs-parent=\"#kioskAccordion\"><div class=\"card-body\"><div class=\"choose-table new-table\"><table class=\"table\"><tbody><tr><td><h5>$1,595<\/h5>(Precio de Lista: $2,495)\r\n\r\n\r\nSe Requiere NRS POS<\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\"><h3 style=\"height: auto;margin-bottom: 0;\">HARDWARE INCLUIDO<\/h3><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\">Quiosco de Autopedido<\/td><\/tr><tr class=\"light-green-color\"><td>Impresora de Recibos Incorporada<\/td><\/tr><tr class=\"light-green-color\"><td>Esc\u00e1ner de C\u00f3digo de Barras<\/td><\/tr><tr class=\"light-green-color\"><td>Pantalla T\u00e1ctil<\/td><\/tr><tr class=\"light-green-color\"><td>Soporte de Piso (+$200 Extra)<\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">NRS PAY<\/h3><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\" style=\"background-color:#d7cae3!important;\">NRS Pay <strong>Requerido<\/strong><\/td><\/tr><tr class=\"light-purple-color\"><td>Lector de Tarjetas de Cr\u00e9dito <strong>Incluido (valor de $200)<\/strong><\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"card\"><div class=\"card-header\" id=\"headingfifty21\"><h5 class=\"mb-0\"><button style=\"margin-bottom: 10px;\" class=\"accordion-button btn btn-link level-1 collapsed\" data-toggle=\"collapse\" data-target=\"#collapsefifty21\" aria-controls=\"collapsefifty21\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapsefifty21\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5>ELIJA SU PLAN DE SOFTWARE <span style=\"white-space: nowrap;\">(POS MRC)<\/span> TARIFAS DE SERVICIO Y SOPORTE DE POS; IMPUESTOS ADICIONALES<p class=\"purple\">TARIFAS MENSUALES DE NRS PAY ADICIONALES SEG\u00daN EL PLAN<\/p><\/h5><\/button><\/h5><\/div><div id=\"collapsefifty21\" class=\"accordion-collapse collapse\" aria-labelledby=\"headingfifty21\" data-parent=\"#accordion6\" data-bs-parent=\"#accordion6\" style=\"display: none;\"><div class=\"card-body\"><div id=\"buzz\"><div class=\"accordion\" id=\"accordion5\"><div class=\"card\"><div class=\"card-header\" id=\"headingfifty6\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link collapsed level-2\" data-toggle=\"collapse\" data-target=\"#collapsefifty6\" aria-expanded=\"true\" aria-controls=\"collapsefifty6\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapsefifty6\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-white mb-0\"><strong>B\u00c1SICO<\/strong><\/h5><\/button><\/h5><\/div><div id=\"collapsefifty6\" class=\"accordion-collapse collapse\" aria-labelledby=\"headingfifty6\" data-parent=\"#accordion5\" data-bs-parent=\"#accordion5\"><div class=\"card-body\"><div class=\"choose-table table2\"><table class=\"table\"><tbody><tr><td>Comience por Menos<\/td><\/tr><tr><td><h5>$19.95\/mes*<\/h5>Sin NRS PAY: <strong>$29.95<\/strong>\/mes<\/td><\/tr><tr><td><p style=\"font-size: 12px; margin-bottom: 0;\"><strong>PAGUE ANUALMENTE Y OBTENGA UN MES GRATIS<\/strong><\/p><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">CARACTER\u00cdSTICAS B\u00c1SICAS<\/h3><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\" style=\"background-color:#d7cae3!important;\"><strong>3<\/strong> Usuarios<\/td><\/tr><tr><td>Ejecute <strong>1<\/strong> Anuncio Orientado al Cliente<\/td><\/tr><tr><td>Permisos de Usuario Personalizados<\/td><\/tr><tr><td>Gesti\u00f3n de Precios e Inventario<\/td><\/tr><tr><td>Estad\u00edsticas de Ventas<\/td><\/tr><tr><td>Soporte por Tel\u00e9fono y Chat (7 d\u00edas a la semana)<\/td><\/tr><tr><td>Gesti\u00f3n Remota: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><\/tr><tr><td>Crear Promociones<\/td><\/tr><tr><td>Correos Electr\u00f3nicos de Resumen Diario de Ventas<\/td><\/tr><tr><td>Imprimir Etiquetas: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><\/tr><tr class=\"light-blue-color\"><td><h5><strong>TERMINALES POS ADICIONALES<\/strong><\/h5>Cualquier plan que elija: <strong>$19.95<\/strong>\/mes por cada m\u00e1quina adicional \u2013 Sin NRS PAY: <strong>$29.95<\/strong>\/mes.<\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><div class=\"card\"><div class=\"card-header\" id=\"headingfifty99\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link collapsed level-2\" data-toggle=\"collapse\" data-target=\"#collapsefifty99\" aria-expanded=\"true\" aria-controls=\"collapsefifty99\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapsefifty99\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-white mb-0\"><strong>PRO<\/strong><\/h5><\/button><\/h5><\/div><div id=\"collapsefifty99\" class=\"accordion-collapse collapse\" aria-labelledby=\"headingfifty99\" data-parent=\"#accordion5\" data-bs-parent=\"#accordion5\"><div class=\"card-body\"><div class=\"choose-table table2\"><table class=\"table\"><tbody><tr><td>Herramientas Comerciales Profesionales<\/td><\/tr><tr><td><h5>$34.95\/ mes*<\/h5>Sin NRS PAY: <strong>$54.95<\/strong>\/mes<\/td><\/tr><tr><td><p style=\"font-size: 12px; margin-bottom: 0;\"><strong>PAGUE ANUALMENTE Y OBTENGA UN MES GRATIS<\/strong><\/p><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">CARACTER\u00cdSTICAS B\u00c1SICAS<\/h3><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\" style=\"background-color:#d7cae3!important;\">Usuarios <strong>Ilimitados<\/strong><\/td><\/tr><tr><td>Ejecute <strong>3<\/strong> Anuncios Orientados al Cliente<\/td><\/tr><tr><td>Permisos de Usuario Personalizados<\/td><\/tr><tr><td>Gesti\u00f3n de Precios e Inventario<\/td><\/tr><tr><td>Estad\u00edsticas de Ventas<\/td><\/tr><tr><td>Soporte por Tel\u00e9fono y Chat (7 d\u00edas a la semana)<\/td><\/tr><tr><td>Gesti\u00f3n Remota: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><\/tr><tr><td>Crear Promociones<\/td><\/tr><tr><td>Correos Electr\u00f3nicos de Resumen Diario de Ventas<\/td><\/tr><tr><td>Imprimir Etiquetas: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><\/tr><tr class=\"lavanda-color\"><td class=\"py-2 px-0\"><h3 class=\"h-auto mb-0\">\u00a1Incluye Herramientas Comerciales Pro!<\/h3><div class=\"d-inline-block w-100\" style=\"height:3px;background:#fff;\"><\/div>Datos Avanzados\r\n\r\n\r\n<span>(Valor de $14.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td class=\"lavanda-color\">Modificadores de Art\u00edculos e Impresora IP Remota\r\n\r\n\r\n<span>(Valor de $14.95\/mes)<\/span>\r\n\r\n\r\n<span>\u2013 Nota: Requiere Compra de Impresora IP de NRS<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td class=\"lavanda-color\">Reloj de Control de Empleados\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Integraci\u00f3n de C\u00e1mara de Seguridad\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span>\r\n\r\n\r\n<span>\u2013 Nota: Requiere Compra de Equipo por Separado<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Cuentas de Clientes\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Anulaci\u00f3n de Gerente Remoto\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr style=\"display: none;\"><td>Recibos por SMS\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr style=\"display: none;\"><td>Escaneo de Identificaci\u00f3n\/Licencia\r\n\r\n\r\n<span>(Valor de $4.95\/mes)<\/span><\/td><\/tr><tr class=\"light-blue-color\"><td><h5><strong>TERMINALES POS ADICIONALES<\/strong><\/h5>Cualquier plan que elija: <strong>$19.95<\/strong>\/mes por cada m\u00e1quina adicional \u2013 Sin NRS PAY: <strong>$29.95<\/strong>\/mes.<\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><div class=\"card\"><div class=\"card-header\" id=\"headingfifty4\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link level-2 collapsed\" data-toggle=\"collapse\" data-target=\"#collapsefifty4\" aria-expanded=\"false\" aria-controls=\"collapsefifty4\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapsefifty4\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-white mb-0\"><strong>AVANZADO<\/strong><\/h5><\/button><\/h5><\/div><div id=\"collapsefifty4\" class=\"accordion-collapse collapse\" aria-labelledby=\"headingfifty4\" data-parent=\"#accordion5\" data-bs-parent=\"#accordion5\" style=\"display: none;\"><div class=\"card-body\"><div class=\"choose-table table2\"><table class=\"table\"><tbody><tr><td>Comercio Electr\u00f3nico y Lealtad Incluidos<\/td><\/tr><tr><td><h5>$49.95\/ mes<\/h5>Sin NRS PAY: <strong>$74.95<\/strong>\/mes<\/td><\/tr><tr><td><p style=\"font-size: 12px; margin-bottom: 0;\"><strong>PAGUE ANUALMENTE Y OBTENGA UN MES GRATIS<\/strong><\/p><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">CARACTER\u00cdSTICAS B\u00c1SICAS<\/h3><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\" style=\"background-color:#d7cae3!important;\">Usuarios <strong>Ilimitados<\/strong><\/td><\/tr><tr><td>Ejecute <strong>3<\/strong> Anuncios Orientados al Cliente<\/td><\/tr><tr><td>Permisos de Usuario Personalizados<\/td><\/tr><tr><td>Gesti\u00f3n de Precios e Inventario<\/td><\/tr><tr><td>Estad\u00edsticas de Ventas<\/td><\/tr><tr><td>Soporte por Tel\u00e9fono y Chat (7 d\u00edas a la semana)<\/td><\/tr><tr><td>Gesti\u00f3n Remota: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><\/tr><tr><td>Crear Promociones<\/td><\/tr><tr><td>Correos Electr\u00f3nicos de Resumen Diario de Ventas<\/td><\/tr><tr><td>Imprimir Etiquetas: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><\/tr><tr class=\"lavanda-color\"><td class=\"py-2 px-0\"><h3 class=\"h-auto mb-0\">\u00a1Incluye <u>TODAS<\/u> las Herramientas Comerciales Pro!<\/h3><div class=\"d-inline-block w-100\" style=\"height:3px;background:#fff;\"><\/div>Datos Avanzados\r\n\r\n\r\n<span>(Valor de $14.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td class=\"lavanda-color\">Modificadores de Art\u00edculos e Impresora IP Remota\r\n\r\n\r\n<span>(Valor de $14.95\/mes)<\/span>\r\n\r\n\r\n<span>\u2013 Nota: Requiere Compra de Impresora IP de NRS<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td class=\"lavanda-color\">Reloj de Control de Empleados\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Integraci\u00f3n de C\u00e1mara de Seguridad\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span>\r\n\r\n\r\n<span>\u2013 Nota: Requiere Compra de Equipo por Separado<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Cuentas de Clientes\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Anulaci\u00f3n de Gerente Remoto\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Alertas Antirrobo\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Recibos por SMS\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Escaneo de Identificaci\u00f3n\/Licencia\r\n\r\n\r\n<span>(Valor de $4.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Proveedores+\r\n\r\n\r\n<span>(Valor de $14.95\/mes)<\/span><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\"><h3 style=\"height: auto;margin-bottom: 0;\">INCLUYE <u>TODAS<\/u> LAS CARACTER\u00cdSTICAS DE COMERCIO ELECTR\u00d3NICO\r\n\r\n\r\n<span>(Valor de $29.95\/mes)<\/span><\/h3><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\">Su Propio Sitio Web de Comercio Electr\u00f3nico<\/td><\/tr><tr class=\"light-green-color\"><td>Vender en la Aplicaci\u00f3n de Compras BOSS Local\r\n\r\n\r\n\u2013 Disponible para sus clientes en Android e iOS<\/td><\/tr><tr class=\"light-green-color\"><td>Red de Entrega de NRS<\/td><\/tr><tr class=\"light-orange-color\"><td><h3 class=\"h-auto mb-0\">INCLUYE <u>TODAS<\/u> LAS CARACTER\u00cdSTICAS DE LEALTAD\r\n\r\n\r\n<span>(Valor de $29.95\/mes)<\/span><\/h3><\/td><\/tr><tr class=\"light-orange-color\"><td>Programa de Puntos de Lealtad<\/td><\/tr><tr class=\"light-orange-color\"><td>Programa de Clubes de Lealtad<\/td><\/tr><tr class=\"light-orange-color\"><td>Historial de Transacciones del Cliente<\/td><\/tr><tr class=\"light-blue-color\"><td><h5><strong>TERMINALES POS ADICIONALES<\/strong><\/h5>Cualquier plan que elija: <strong>$19.95<\/strong>\/mes por cada m\u00e1quina adicional \u2013 Sin NRS PAY: <strong>$29.95<\/strong>\/mes.<\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><div class=\"card\"><div class=\"card-header\" id=\"headingfifty5\"><h5 class=\"mb-0\"><button class=\"accordion-button btn btn-link level-2 collapsed\" data-toggle=\"collapse\" data-target=\"#collapsefifty5\" aria-expanded=\"false\" aria-controls=\"collapsefifty5\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapsefifty5\"><i class=\"fa\" aria-hidden=\"true\"><\/i><h5 class=\"text-white mb-0\"><strong>\u00c9LITE<\/strong><\/h5><\/button><\/h5><\/div><div id=\"collapsefifty5\" class=\"accordion-collapse collapse\" aria-labelledby=\"headingfifty5\" data-parent=\"#accordion5\" data-bs-parent=\"#accordion5\" style=\"display: none;\"><div class=\"card-body\"><div class=\"choose-table table2\"><table class=\"table\"><tbody><tr><td>\u00a1Contacte a sus Clientes!<\/td><\/tr><tr><td><h5>$79.95\/ mes*<\/h5>Sin NRS PAY: <strong>$109.95<\/strong>\/mes<\/td><\/tr><tr><td><p style=\"font-size: 12px; margin-bottom: 0;\"><strong>PAGUE ANUALMENTE Y OBTENGA UN MES GRATIS<\/strong><\/p><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\"><h3 style=\"height: auto;font-size:18px;\" class=\"section-title mb-0\">CARACTER\u00cdSTICAS B\u00c1SICAS<\/h3><\/td><\/tr><tr class=\"light-purple-color\"><td class=\"light-purple-color\" style=\"background-color:#d7cae3!important;\">Usuarios <strong>Ilimitados<\/strong><\/td><\/tr><tr><td>Ejecute <strong>3<\/strong> Anuncios Orientados al Cliente<\/td><\/tr><tr><td>Permisos de Usuario Personalizados<\/td><\/tr><tr><td>Gesti\u00f3n de Precios e Inventario<\/td><\/tr><tr><td>Estad\u00edsticas de Ventas<\/td><\/tr><tr><td>Soporte por Tel\u00e9fono y Chat (7 d\u00edas a la semana)<\/td><\/tr><tr><td>Gesti\u00f3n Remota: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><\/tr><tr><td>Crear Promociones<\/td><\/tr><tr><td>Correos Electr\u00f3nicos de Resumen Diario de Ventas<\/td><\/tr><tr><td>Imprimir Etiquetas: Aplicaci\u00f3n M\u00f3vil y Portal de Escritorio<\/td><\/tr><tr class=\"lavanda-color\"><td class=\"py-2 px-0\"><h3 class=\"h-auto mb-0\">\u00a1Incluye <u>TODAS<\/u> las Herramientas Comerciales Pro!<\/h3><div class=\"d-inline-block w-100\" style=\"height:3px;background:#fff;\"><\/div>Datos Avanzados\r\n\r\n\r\n<span>(Valor de $14.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td class=\"lavanda-color\">Modificadores de Art\u00edculos e Impresora IP Remota\r\n\r\n\r\n<span>(Valor de $14.95\/mes)<\/span>\r\n\r\n\r\n<span>\u2013 Nota: Requiere Compra de Impresora IP de NRS<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td class=\"lavanda-color\">Reloj de Control de Empleados\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Integraci\u00f3n de C\u00e1mara de Seguridad\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span>\r\n\r\n\r\n<span>\u2013 Nota: Requiere Compra de Equipo por Separado<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Cuentas de Clientes\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Anulaci\u00f3n de Gerente Remoto\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Alertas Antirrobo\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Recibos por SMS\r\n\r\n\r\n<span>(Valor de $9.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Escaneo de Identificaci\u00f3n\/Licencia\r\n\r\n\r\n<span>(Valor de $4.95\/mes)<\/span><\/td><\/tr><tr class=\"lavanda-color\"><td>Proveedores+\r\n\r\n\r\n<span>(Valor de $14.95\/mes)<\/span><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\"><h3 style=\"height: auto;margin-bottom: 0;\">INCLUYE <u>TODAS<\/u> LAS CARACTER\u00cdSTICAS DE COMERCIO ELECTR\u00d3NICO\r\n\r\n\r\n<span>(Valor de $29.95\/mes)<\/span><\/h3><\/td><\/tr><tr class=\"light-green-color\"><td class=\"light-green-color\">Su Propio Sitio Web de Comercio Electr\u00f3nico<\/td><\/tr><tr class=\"light-green-color\"><td>Vender en la Aplicaci\u00f3n de Compras BOSS Local\r\n\r\n\r\n\u2013 Disponible para sus clientes en Android e iOS<\/td><\/tr><tr class=\"light-green-color\"><td>Red de Entrega de NRS<\/td><\/tr><tr class=\"light-orange-color\"><td><h3 class=\"h-auto mb-0\">INCLUYE <u>TODAS<\/u> LAS CARACTER\u00cdSTICAS DE LEALTAD\r\n\r\n\r\n<span>(Valor de $29.95\/mes)<\/span><\/h3><\/td><\/tr><tr class=\"light-orange-color\"><td>Programa de Puntos de Lealtad<\/td><\/tr><tr class=\"light-orange-color\"><td>Programa de Clubes de Lealtad<\/td><\/tr><tr class=\"light-orange-color\"><td>Historial de Transacciones del Cliente<\/td><\/tr><tr class=\"light-pink-color\"><td><h3 class=\"h-auto mb-0\">\u00a1INCLUYE <u>TODOS<\/u> los Servicios de Marketing!\r\n\r\n\r\n<span>(Valor de $79.90\/mes)*<\/span><\/h3><\/td><\/tr><tr class=\"light-pink-color\"><td>Contactar a mis Clientes<\/td><\/tr><tr class=\"light-pink-color\"><td>Recomendaciones de Productos con IA<\/td><\/tr><tr class=\"light-blue-color\"><td><h5><strong>TERMINALES POS ADICIONALES<\/strong><\/h5>Cualquier plan que elija: <strong>$19.95<\/strong>\/mes por cada m\u00e1quina adicional \u2013 Sin NRS PAY: <strong>$29.95<\/strong>\/mes.<\/td><\/tr><\/tbody><\/table><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><p class=\"para-text1\"><a href=\"https:\/\/nrsplus.com\/es\/precios-mas-opciones\/\">CONTINUAR PARA VER M\u00c1S OPCIONES<\/a><\/p><p class=\"para-text\">DESCARGUE LAS HOJAS DE PRECIOS:<a href=\"\" target=\"_blank\" rel=\"noopener\">[ENGLISH]<\/a> \u2022 <a href=\"\" target=\"_blank\" rel=\"noopener\">[ESPA\u00d1OL]<\/a><\/p><hr \/><div id=\"contact-form1\"><div class=\"col-md-12\"><div style=\"max-width: 700px; margin: 0 auto;\"><h5 class=\"sideLinetext text-center\"><b style=\"color: #7d608d; font-size: 23px;\">\u00bfListo para comprar? Comience aqu\u00ed.<\/b><p style=\"font-size: 18px;\">Por favor env\u00ede este formulario y un agente de ventas se comunicar\u00e1 con usted en breve.<\/p><\/h5><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework new-form-validation_wrapper center-btn-form_wrapper' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_4' ><div id='gf_4' class='gform_anchor' tabindex='-1'><\/div>\n                        <div class='gform_heading'>\n\t\t\t\t\t\t\t<p class='gform_required_legend'>&quot;<span class=\"gfield_required gfield_required_asterisk\">*<\/span>&quot; se\u00f1ala los campos obligatorios<\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_4' id='gform_4' class='new-form-validation center-btn-form' action='\/es\/wp-json\/wp\/v2\/pages\/48587#gf_4' data-formid='4' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_4' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_4_18\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_18'>Comments<\/label><div class='ginput_container'><input name='input_18' id='input_4_18' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_4_18'>Este campo es un campo de validaci\u00f3n y debe quedar sin cambios.<\/div><\/div><div id=\"field_4_1\" class=\"gfield gfield--type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_1'>Nombre completo<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_4_1' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_4_5\" class=\"gfield gfield--type-phone gfield--width-half gfield_contains_required field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_5'>N\u00famero de tel\u00e9fono<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_5' id='input_4_5' type='tel' value='' class='large'   aria-required=\"true\" aria-invalid=\"false\" aria-describedby=\"gfield_description_4_5\"  \/><\/div><div class='gfield_description' id='gfield_description_4_5'>Nota: s\u00f3lo para EE.UU. y Canad\u00e1<\/div><\/div><div id=\"field_4_4\" class=\"gfield gfield--type-email gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_4'>Correo electr\u00f3nico<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_4' id='input_4_4' type='email' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_4_2\" class=\"gfield gfield--type-text gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_2'>Nombre de la tienda\/negocio<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_2' id='input_4_2' type='text' value='' class='large'     aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_4_16\" class=\"gfield gfield--type-text gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_16'>N\u00famero de identificaci\u00f3n del terminal POS<\/label><div class='ginput_container ginput_container_text'><input name='input_16' id='input_4_16' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_4_17\" class=\"gfield gfield--type-text gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_4_17'>\u00bfQui\u00e9n es su agente de ventas de NRS?<\/label><div class='ginput_container ginput_container_text'><input name='input_17' id='input_4_17' type='text' value='' class='large'      aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_4_6\" class=\"gfield gfield--type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_6' id='input_4_6' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_4_9\" class=\"gfield gfield--type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_9' id='input_4_9' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_4_10\" class=\"gfield gfield--type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_10' id='input_4_10' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_4_12\" class=\"gfield gfield--type-html under-fields-form-text tmark gfield_html gfield_html_formatted gfield_no_follows_desc field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><p class=\"under-fields-form-text\">*Al enviar la informaci\u00f3n anterior, acepta nuestra <a class=\"text-decoration-underline\" href=\"https:\/\/nrsplus.com\/privacy-policy\/\" target=\"_blank\" rel=\"noopener\">pol\u00edtica de privacidad<\/a> y <a class=\"text-decoration-underline\" href=\"https:\/\/nrsplus.com\/terms-of-use\/\" target=\"_blank\" rel=\"noopener\">t\u00e9rminos<\/a >, que afectan sus derechos, y consiente que NRS se comunique con usted por correo electr\u00f3nico recurrente o lo llame, por mensaje de texto, marcaci\u00f3n directa, usando un sistema automatizado o voz pregrabada y\/o usando inteligencia artificial para discutir los productos y servicios de NRS. No se requiere consentimiento para recibir ning\u00fan servicio y usted puede optar por no recibirlo en cualquier momento.<\/p><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <input type='submit' id='gform_submit_button_4' class='gform_button button' onclick='gform.submission.handleButtonClick(this);' data-submission-type='submit' value='Entregar'  \/> <input type='hidden' name='gform_ajax' value='form_id=4&amp;title=&amp;description=&amp;tabindex=0&amp;theme=gravity-theme&amp;styles=[]&amp;hash=31546c870530fdbfe51955fe9733a6bf' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_4' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_4' id='gform_theme_4' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_4' id='gform_style_settings_4' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_4' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='4' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='USD' value='\/elJpKBVxDnvtlkL\/rBb0bKd74H8cY6W7gAE54B82b2T744Nv9ekjIchC7uHvfxnzVQwc17IZOsKcVISO4X2JjwZXn64mYv09W+nmNyyaVbPRto=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_4' value='WyJbXSIsImU4ZmFkZjY4MTAxYTE4MzkyMWJkNTEzYWU5N2IyMmIyIl0=' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_4' id='gform_target_page_number_4' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_4' id='gform_source_page_number_4' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_4' id='gform_ajax_frame_4' title='Este iframe contiene la l\u00f3gica necesaria para gestionar formularios con ajax activado.'><\/iframe>\n\t\t                <script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 4, 'https:\/\/nrsplus.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_4').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_4');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_4').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_4').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_4').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_4').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_4').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_4').val();gformInitSpinner( 4, 'https:\/\/nrsplus.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [4, current_page]);window['gf_submitting_4'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_4').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_4').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [4]);window['gf_submitting_4'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_4').text());}else{jQuery('#gform_4').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"4\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_4\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_4\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_4\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 4, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n<\/div><p class=\"legal-text mt-0\">*Precios aplicables solo si el cliente se inscribe en el servicio NRS Pay. Si el cliente cancela el servicio NRS Pay anticipadamente, se le cobrar\u00e1n los precios est\u00e1ndar de POS y deber\u00e1 devolver cualquier descuento de equipo recibido. Consulte el contrato para m\u00e1s detalles.<\/p><p class=\"legal-text mt-0\">POS: Los precios y descuentos entran en vigencia a partir de la fecha del documento y est\u00e1n sujetos a cambios previo aviso, cuando el aviso est\u00e9 disponible. Consulte los precios disponibles en www.nrsplus.com\/pricing. Se requiere contrato. La tarifa de servicio del POS cubre solo servicio y soporte. Todos los pagos anticipados no son reembolsables. Las tarifas de servicio y las funciones adicionales pueden estar sujetas a t\u00e9rminos adicionales, y algunas requieren la compra de equipo adicional, ya sea de NRS o de un tercero. Algunos programas son operados por terceros y la elegibilidad y los t\u00e9rminos de dichos programas son determinados por los terceros. NRS se reserva el derecho de cambiar o terminar las ofertas y programas sin previo aviso. Consulte www.nrsplus.com para obtener todos los detalles.<\/p><p class=\"legal-text mt-0\">NRS Pay: NRS Pay es un servicio de National Retail Solutions, Inc. Se requiere contrato. Ciertas funciones no son est\u00e1ndar y pueden requerir cargos adicionales. El programa NRS Pay Cash Discount es un servicio adicional premium que est\u00e1 sujeto a una estructura de tarifas adicional y t\u00e9rminos y condiciones adicionales; se aplica una tarifa mensual de $49.95; la tarifa no se cobra si se procesan m\u00e1s de $18k\/mes; el comerciante debe cumplir con todas las leyes aplicables y las condiciones de la red de pago. Si el hardware se compra como un paquete con NRS Pay (u otro(s) servicio(s) seg\u00fan corresponda) y el procesamiento\/servicio(s) no se utilizan o se cancelan antes de que finalice un a\u00f1o, se evaluar\u00e1 una tarifa de actualizaci\u00f3n para el hardware de POS, basada en el MSRP. T\u00e9rminos sujetos a cambios. National Retail Solutions, Inc. es un MSP\/ISO registrado de Elavon, Inc., Georgia, una subsidiaria de propiedad total de U.S. Bancorp, Minneapolis, MN, y un ISO registrado de Wells Fargo Bank, N.A., Concord, CA. IDT Telecom Canada Corp. es un MSP\/ISO registrado de Elavon, Inc., Georgia, una subsidiaria de propiedad total de U.S. Bancorp, Minneapolis, MN. Se requiere unidad POS de NRS, Simba o Panther \u2013 se requiere contrato separado. Pregunte para m\u00e1s detalles.<\/p><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"Precios(833) 289-2767NRSPLUS.COM\/PRICINGELIJA SU HARDWARE NRS POSPRECIOS DE EQUIPOS; IMPUESTOS ADICIONALESPAQUETES POS DE MOSTRADORPAQUETES POS DE TABLETATERMINAL DE QUIOSCOPUMA POS$1,299(Precio de [&hellip;]","protected":false},"author":415,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"class_list":["post-48587","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Precios de TPV | Soluciones nacionales para minoristas<\/title>\n<meta name=\"description\" content=\"Disfrute de un procesamiento de tarjetas de cr\u00e9dito a bajo coste con NRS Pay y acceda a funciones como comercio electr\u00f3nico y programas de fidelizaci\u00f3n, alarma antip\u00e1nico, datos de escaneado de tabaco y mucho m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/nrsplus.com\/es\/precios\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Precios\" \/>\n<meta property=\"og:description\" content=\"Disfrute de un procesamiento de tarjetas de cr\u00e9dito a bajo coste con NRS Pay y acceda a funciones como comercio electr\u00f3nico y programas de fidelizaci\u00f3n, alarma antip\u00e1nico, datos de escaneado de tabaco y mucho m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/nrsplus.com\/es\/precios\/\" \/>\n<meta property=\"og:site_name\" content=\"National Retail Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-23T15:48:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/nrsplus.com\/wp-content\/uploads\/2023\/06\/img-nrs2-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"31 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/nrsplus.com\\\/es\\\/precios\\\/\",\"url\":\"https:\\\/\\\/nrsplus.com\\\/es\\\/precios\\\/\",\"name\":\"Precios de TPV | Soluciones nacionales para minoristas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/nrsplus.com\\\/es\\\/#website\"},\"datePublished\":\"2021-04-12T19:45:26+00:00\",\"dateModified\":\"2026-04-23T15:48:16+00:00\",\"description\":\"Disfrute de un procesamiento de tarjetas de cr\u00e9dito a bajo coste con NRS Pay y acceda a funciones como comercio electr\u00f3nico y programas de fidelizaci\u00f3n, alarma antip\u00e1nico, datos de escaneado de tabaco y mucho m\u00e1s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/nrsplus.com\\\/es\\\/precios\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/nrsplus.com\\\/es\\\/precios\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/nrsplus.com\\\/es\\\/precios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/nrsplus.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Precios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/nrsplus.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/nrsplus.com\\\/es\\\/\",\"name\":\"National Retail Solutions\",\"description\":\"The All-in-one Point Of Sale System For Your Retail Business\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/nrsplus.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Precios de TPV | Soluciones nacionales para minoristas","description":"Disfrute de un procesamiento de tarjetas de cr\u00e9dito a bajo coste con NRS Pay y acceda a funciones como comercio electr\u00f3nico y programas de fidelizaci\u00f3n, alarma antip\u00e1nico, datos de escaneado de tabaco y mucho m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/nrsplus.com\/es\/precios\/","og_locale":"es_ES","og_type":"article","og_title":"Precios","og_description":"Disfrute de un procesamiento de tarjetas de cr\u00e9dito a bajo coste con NRS Pay y acceda a funciones como comercio electr\u00f3nico y programas de fidelizaci\u00f3n, alarma antip\u00e1nico, datos de escaneado de tabaco y mucho m\u00e1s.","og_url":"https:\/\/nrsplus.com\/es\/precios\/","og_site_name":"National Retail Solutions","article_modified_time":"2026-04-23T15:48:16+00:00","og_image":[{"width":1000,"height":523,"url":"https:\/\/nrsplus.com\/wp-content\/uploads\/2023\/06\/img-nrs2-min.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"31 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/nrsplus.com\/es\/precios\/","url":"https:\/\/nrsplus.com\/es\/precios\/","name":"Precios de TPV | Soluciones nacionales para minoristas","isPartOf":{"@id":"https:\/\/nrsplus.com\/es\/#website"},"datePublished":"2021-04-12T19:45:26+00:00","dateModified":"2026-04-23T15:48:16+00:00","description":"Disfrute de un procesamiento de tarjetas de cr\u00e9dito a bajo coste con NRS Pay y acceda a funciones como comercio electr\u00f3nico y programas de fidelizaci\u00f3n, alarma antip\u00e1nico, datos de escaneado de tabaco y mucho m\u00e1s.","breadcrumb":{"@id":"https:\/\/nrsplus.com\/es\/precios\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/nrsplus.com\/es\/precios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/nrsplus.com\/es\/precios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/nrsplus.com\/es\/"},{"@type":"ListItem","position":2,"name":"Precios"}]},{"@type":"WebSite","@id":"https:\/\/nrsplus.com\/es\/#website","url":"https:\/\/nrsplus.com\/es\/","name":"National Retail Solutions","description":"The All-in-one Point Of Sale System For Your Retail Business","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/nrsplus.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/nrsplus.com\/es\/wp-json\/wp\/v2\/pages\/48587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nrsplus.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nrsplus.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nrsplus.com\/es\/wp-json\/wp\/v2\/users\/415"}],"replies":[{"embeddable":true,"href":"https:\/\/nrsplus.com\/es\/wp-json\/wp\/v2\/comments?post=48587"}],"version-history":[{"count":9,"href":"https:\/\/nrsplus.com\/es\/wp-json\/wp\/v2\/pages\/48587\/revisions"}],"predecessor-version":[{"id":83348,"href":"https:\/\/nrsplus.com\/es\/wp-json\/wp\/v2\/pages\/48587\/revisions\/83348"}],"wp:attachment":[{"href":"https:\/\/nrsplus.com\/es\/wp-json\/wp\/v2\/media?parent=48587"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nrsplus.com\/es\/wp-json\/wp\/v2\/tags?post=48587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}